{"id":4952,"date":"2021-01-18T14:07:19","date_gmt":"2021-01-18T13:07:19","guid":{"rendered":"https:\/\/www.haydn.it\/orchestra"},"modified":"2026-02-20T11:14:37","modified_gmt":"2026-02-20T10:14:37","slug":"orchester","status":"publish","type":"page","link":"https:\/\/www.haydn.it\/de\/orchester","title":{"rendered":"Orchester"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":4795,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-orchestra.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4952","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Haydn Orchester | Stiftung Haydn<\/title>\n<meta name=\"description\" content=\"Das Haydn Orchester ist ein eingespieltes Team, das mit seiner Experimentierfreude und einem breiten Repertoire zwischen Symphonie und Kammermusik \u00fcberzeugt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Haydn Orchester | Stiftung Haydn\" \/>\n<meta property=\"og:description\" content=\"Das Haydn Orchester ist ein eingespieltes Team, das mit seiner Experimentierfreude und einem breiten Repertoire zwischen Symphonie und Kammermusik \u00fcberzeugt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.haydn.it\/de\/orchester\" \/>\n<meta property=\"og:site_name\" content=\"Stiftung Haydn\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-20T10:14:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.haydn.it\/wp-content\/uploads\/2021\/04\/orchestra_03_2250x1070.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.haydn.it\/wp-content\/uploads\/2021\/04\/orchestra_03_2250x1070.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.haydn.it\/de\/orchester\",\"url\":\"https:\/\/www.haydn.it\/de\/orchester\",\"name\":\"Haydn Orchester | Stiftung Haydn\",\"isPartOf\":{\"@id\":\"https:\/\/www.haydn.it\/de#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.haydn.it\/de\/orchester#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.haydn.it\/de\/orchester#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.haydn.it\/wp-content\/uploads\/2021\/04\/orchestra_03_1200x1410.jpg\",\"datePublished\":\"2021-01-18T13:07:19+00:00\",\"dateModified\":\"2026-02-20T10:14:37+00:00\",\"description\":\"Das Haydn Orchester ist ein eingespieltes Team, das mit seiner Experimentierfreude und einem breiten Repertoire zwischen Symphonie und Kammermusik \u00fcberzeugt.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.haydn.it\/de\/orchester#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.haydn.it\/de\/orchester\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.haydn.it\/de\/orchester#primaryimage\",\"url\":\"https:\/\/www.haydn.it\/wp-content\/uploads\/2021\/04\/orchestra_03_1200x1410.jpg\",\"contentUrl\":\"https:\/\/www.haydn.it\/wp-content\/uploads\/2021\/04\/orchestra_03_1200x1410.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Das Orchester\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.haydn.it\/de\/orchester#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.haydn.it\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Orchester\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.haydn.it\/de#website\",\"url\":\"https:\/\/www.haydn.it\/de\",\"name\":\"Stiftung Haydn\",\"description\":\"Fondazione Haydn Stiftung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.haydn.it\/de?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Haydn Orchester | Stiftung Haydn","description":"Das Haydn Orchester ist ein eingespieltes Team, das mit seiner Experimentierfreude und einem breiten Repertoire zwischen Symphonie und Kammermusik \u00fcberzeugt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Haydn Orchester | Stiftung Haydn","og_description":"Das Haydn Orchester ist ein eingespieltes Team, das mit seiner Experimentierfreude und einem breiten Repertoire zwischen Symphonie und Kammermusik \u00fcberzeugt.","og_url":"https:\/\/www.haydn.it\/de\/orchester","og_site_name":"Stiftung Haydn","article_modified_time":"2026-02-20T10:14:37+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.haydn.it\/wp-content\/uploads\/2021\/04\/orchestra_03_2250x1070.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/www.haydn.it\/wp-content\/uploads\/2021\/04\/orchestra_03_2250x1070.jpg","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.haydn.it\/de\/orchester","url":"https:\/\/www.haydn.it\/de\/orchester","name":"Haydn Orchester | Stiftung Haydn","isPartOf":{"@id":"https:\/\/www.haydn.it\/de#website"},"primaryImageOfPage":{"@id":"https:\/\/www.haydn.it\/de\/orchester#primaryimage"},"image":{"@id":"https:\/\/www.haydn.it\/de\/orchester#primaryimage"},"thumbnailUrl":"https:\/\/www.haydn.it\/wp-content\/uploads\/2021\/04\/orchestra_03_1200x1410.jpg","datePublished":"2021-01-18T13:07:19+00:00","dateModified":"2026-02-20T10:14:37+00:00","description":"Das Haydn Orchester ist ein eingespieltes Team, das mit seiner Experimentierfreude und einem breiten Repertoire zwischen Symphonie und Kammermusik \u00fcberzeugt.","breadcrumb":{"@id":"https:\/\/www.haydn.it\/de\/orchester#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.haydn.it\/de\/orchester"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.haydn.it\/de\/orchester#primaryimage","url":"https:\/\/www.haydn.it\/wp-content\/uploads\/2021\/04\/orchestra_03_1200x1410.jpg","contentUrl":"https:\/\/www.haydn.it\/wp-content\/uploads\/2021\/04\/orchestra_03_1200x1410.jpg","width":1200,"height":1200,"caption":"Das Orchester"},{"@type":"BreadcrumbList","@id":"https:\/\/www.haydn.it\/de\/orchester#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.haydn.it\/de"},{"@type":"ListItem","position":2,"name":"Orchester"}]},{"@type":"WebSite","@id":"https:\/\/www.haydn.it\/de#website","url":"https:\/\/www.haydn.it\/de","name":"Stiftung Haydn","description":"Fondazione Haydn Stiftung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.haydn.it\/de?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.haydn.it\/de\/wp-json\/wp\/v2\/pages\/4952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haydn.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.haydn.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.haydn.it\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.haydn.it\/de\/wp-json\/wp\/v2\/comments?post=4952"}],"version-history":[{"count":0,"href":"https:\/\/www.haydn.it\/de\/wp-json\/wp\/v2\/pages\/4952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.haydn.it\/de\/wp-json\/wp\/v2\/media\/4795"}],"wp:attachment":[{"href":"https:\/\/www.haydn.it\/de\/wp-json\/wp\/v2\/media?parent=4952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}